{"id":1700,"date":"2020-04-22T04:57:43","date_gmt":"2020-04-22T04:57:43","guid":{"rendered":"https:\/\/dinetra.com\/?post_type=product&#038;p=1700"},"modified":"2026-01-28T09:14:54","modified_gmt":"2026-01-28T09:14:54","slug":"ines","status":"publish","type":"product","link":"https:\/\/dinetra.com\/en\/product\/ines\/","title":{"rendered":"INES"},"content":{"rendered":"<p> <\/p>","protected":false},"excerpt":{"rendered":"<h3><em>Jachet mod. Ines<\/em><\/h3>\n<ul>\n<li>Unlined<\/li>\n<li>Rever collar<\/li>\n<li>3 buttons, 2 patch pockets<\/li>\n<li>Slits on the back and on the sleeves<\/li>\n<li>Fabric: 65% polyester, 35% cotton<\/li>\n<li>Easy care<\/li>\n<li>Machine wash at 40\u00b0C, gentle cycle<\/li>\n<li>The model is 168 cm high and wears a size 40<\/li>\n<li><\/li>\n<\/ul>\n","protected":false},"featured_media":1708,"template":"","meta":{"iawp_total_views":31},"product_brand":[],"product_cat":[62],"product_tag":[],"class_list":{"0":"post-1700","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-giacche-donna-ristorante-catering","8":"first","9":"outofstock","10":"shipping-taxable","11":"purchasable","12":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>INES - Dinetra<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dinetra.com\/en\/product\/ines\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"INES - Dinetra\" \/>\n<meta property=\"og:description\" content=\"Jachet mod. Ines   Unlined  Rever collar  3 buttons, 2 patch pockets  Slits on the back and on the sleeves  Fabric: 65% polyester, 35% cotton  Easy care  Machine wash at 40\u00b0C, gentle cycle  The model is 168 cm high and wears a size 40\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dinetra.com\/en\/product\/ines\/\" \/>\n<meta property=\"og:site_name\" content=\"Dinetra\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DinetraUniforms\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-28T09:14:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dinetra.com\/wp-content\/uploads\/2020\/04\/IMG_7259-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1707\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dinetra.com\\\/en\\\/product\\\/ines\\\/\",\"url\":\"https:\\\/\\\/dinetra.com\\\/en\\\/product\\\/ines\\\/\",\"name\":\"INES - Dinetra\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dinetra.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dinetra.com\\\/en\\\/product\\\/ines\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dinetra.com\\\/product\\\/ines\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dinetra.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/IMG_7259-scaled.jpg\",\"datePublished\":\"2020-04-22T04:57:43+00:00\",\"dateModified\":\"2026-01-28T09:14:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dinetra.com\\\/en\\\/product\\\/ines\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/dinetra.com\\\/en\\\/product\\\/ines\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dinetra.com\\\/en\\\/product\\\/ines\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dinetra.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/IMG_7259-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/dinetra.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/IMG_7259-scaled.jpg\",\"width\":1707,\"height\":2560,\"caption\":\"Giacca da servizio\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dinetra.com\\\/en\\\/product\\\/ines\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dinetra.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/dinetra.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"INES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dinetra.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/dinetra.com\\\/en\\\/\",\"name\":\"Dinetra\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/dinetra.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dinetra.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dinetra.com\\\/en\\\/#organization\",\"name\":\"Dinetra Uniforms\",\"url\":\"https:\\\/\\\/dinetra.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dinetra.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dinetra.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Logo_Dinetra-02.jpg\",\"contentUrl\":\"https:\\\/\\\/dinetra.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Logo_Dinetra-02.jpg\",\"width\":2084,\"height\":2084,\"caption\":\"Dinetra Uniforms\"},\"image\":{\"@id\":\"https:\\\/\\\/dinetra.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DinetraUniforms\",\"https:\\\/\\\/www.instagram.com\\\/dinetrauniforms\\\/?hl=it\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/66720753\\\/\",\"https:\\\/\\\/www.pinterest.it\\\/DinetraUniforms\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"INES - Dinetra","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dinetra.com\/en\/product\/ines\/","og_locale":"en_US","og_type":"article","og_title":"INES - Dinetra","og_description":"Jachet mod. Ines   Unlined  Rever collar  3 buttons, 2 patch pockets  Slits on the back and on the sleeves  Fabric: 65% polyester, 35% cotton  Easy care  Machine wash at 40\u00b0C, gentle cycle  The model is 168 cm high and wears a size 40","og_url":"https:\/\/dinetra.com\/en\/product\/ines\/","og_site_name":"Dinetra","article_publisher":"https:\/\/www.facebook.com\/DinetraUniforms","article_modified_time":"2026-01-28T09:14:54+00:00","og_image":[{"width":1707,"height":2560,"url":"https:\/\/dinetra.com\/wp-content\/uploads\/2020\/04\/IMG_7259-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dinetra.com\/en\/product\/ines\/","url":"https:\/\/dinetra.com\/en\/product\/ines\/","name":"INES - Dinetra","isPartOf":{"@id":"https:\/\/dinetra.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dinetra.com\/en\/product\/ines\/#primaryimage"},"image":{"@id":"https:\/\/dinetra.com\/product\/ines\/#primaryimage"},"thumbnailUrl":"https:\/\/dinetra.com\/wp-content\/uploads\/2020\/04\/IMG_7259-scaled.jpg","datePublished":"2020-04-22T04:57:43+00:00","dateModified":"2026-01-28T09:14:54+00:00","breadcrumb":{"@id":"https:\/\/dinetra.com\/en\/product\/ines\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/dinetra.com\/en\/product\/ines\/"]]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dinetra.com\/en\/product\/ines\/#primaryimage","url":"https:\/\/dinetra.com\/wp-content\/uploads\/2020\/04\/IMG_7259-scaled.jpg","contentUrl":"https:\/\/dinetra.com\/wp-content\/uploads\/2020\/04\/IMG_7259-scaled.jpg","width":1707,"height":2560,"caption":"Giacca da servizio"},{"@type":"BreadcrumbList","@id":"https:\/\/dinetra.com\/en\/product\/ines\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dinetra.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/dinetra.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"INES"}]},{"@type":"WebSite","@id":"https:\/\/dinetra.com\/en\/#website","url":"https:\/\/dinetra.com\/en\/","name":"Dinetra","description":"","publisher":{"@id":"https:\/\/dinetra.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dinetra.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dinetra.com\/en\/#organization","name":"Dinetra Uniforms","url":"https:\/\/dinetra.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dinetra.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/dinetra.com\/wp-content\/uploads\/2020\/07\/Logo_Dinetra-02.jpg","contentUrl":"https:\/\/dinetra.com\/wp-content\/uploads\/2020\/07\/Logo_Dinetra-02.jpg","width":2084,"height":2084,"caption":"Dinetra Uniforms"},"image":{"@id":"https:\/\/dinetra.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DinetraUniforms","https:\/\/www.instagram.com\/dinetrauniforms\/?hl=it","https:\/\/www.linkedin.com\/company\/66720753\/","https:\/\/www.pinterest.it\/DinetraUniforms\/"]}]}},"_links":{"self":[{"href":"https:\/\/dinetra.com\/en\/wp-json\/wp\/v2\/product\/1700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dinetra.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dinetra.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dinetra.com\/en\/wp-json\/wp\/v2\/media\/1708"}],"wp:attachment":[{"href":"https:\/\/dinetra.com\/en\/wp-json\/wp\/v2\/media?parent=1700"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dinetra.com\/en\/wp-json\/wp\/v2\/product_brand?post=1700"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dinetra.com\/en\/wp-json\/wp\/v2\/product_cat?post=1700"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dinetra.com\/en\/wp-json\/wp\/v2\/product_tag?post=1700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}